{"id":3694,"date":"2020-03-05T09:59:24","date_gmt":"2020-03-05T09:59:24","guid":{"rendered":"http:\/\/cabezaldeimpresion.belgraf.es\/?page_id=3694"},"modified":"2021-10-19T11:51:03","modified_gmt":"2021-10-19T11:51:03","slug":"contacto","status":"publish","type":"page","link":"https:\/\/www.cabezaldeimpresion.com\/zh\/contacto\/","title":{"rendered":"\u8054\u7cfb"},"content":{"rendered":"<div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1581064010419 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-offset-0 vc_col-md-offset-0 vc_col-sm-offset-0\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5>\u5728\u8fd9\u91cc\u627e\u5230\u6211\u4eec<\/h5>\n\n\t\t<\/div> \n\t<\/div> \t<div class=\"vc_empty_space\"  style=\"height: 30px\" ><span\r\n\t\t\tclass=\"vc_empty_space_inner\">\r\n\t\t\t<span class=\"empty_space_image\"  ><\/span>\r\n\t\t<\/span><\/div>\r\n\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>\u6253\u5370\u5934<\/strong><\/p>\n\n\t\t<\/div> \n\t<\/div> \t<div class=\"vc_empty_space\"  style=\"height: 20px\" ><span\r\n\t\t\tclass=\"vc_empty_space_inner\">\r\n\t\t\t<span class=\"empty_space_image\"  ><\/span>\r\n\t\t<\/span><\/div>\r\n\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><a href=\"https:\/\/www.google.com\/maps\/place\/Av.+Redondela,+60,+36320+Redondela,+Pontevedra\/@42.2677729,-8.6690513,17z\/data=!3m1!4b1!4m5!3m4!1s0xd2f632ec9dcee5b:0xec89991cd3a2aa77!8m2!3d42.267769!4d-8.6668626\" target=\"_blank\" rel=\"noopener noreferrer\"><i class=\"fa fa-map\"><\/i> Avenida Redondela 60. 36320-Chapela\uff08Redondela\uff09\u897f\u73ed\u7259<\/a><\/p>\n\n\t\t<\/div> \n\t<\/div> \t<div class=\"vc_empty_space\"  style=\"height: 20px\" ><span\r\n\t\t\tclass=\"vc_empty_space_inner\">\r\n\t\t\t<span class=\"empty_space_image\"  ><\/span>\r\n\t\t<\/span><\/div>\r\n\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><a href=\"tel:+34986335022\"><i class=\"fa fa-phone\"><\/i> +34 986335022<\/a><\/p>\n\n\t\t<\/div> \n\t<\/div> <div class=\"vc_text_separator wpb_content_element full separator_align_center\"><div style=''><span><\/span><\/div><\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u60a8\u9700\u8981\u63a5\u53d7\u6211\u4eec\u7684 <a href=\"https:\/\/www.cabezaldeimpresion.com\/zh\/politica-de-privacidad-2\/\">\u9690\u79c1\u653f\u7b56 <\/a> \u5728\u63d0\u4ea4\u6b64\u95ee\u5377\u4e4b\u524d\u3002<\/p>\n<p><strong>\u6570\u636e\u4fdd\u62a4\u7684\u57fa\u672c\u4fe1\u606f<\/strong><br \/>\n\u8d1f\u8d23\u4eba\uff1a BELTRAN MU\u00d1OZ, .SL<br \/>\n\u76ee\u7684\uff1a\u54cd\u5e94\u901a\u8fc7 Web \u8868\u5355\u63d0\u51fa\u7684\u67e5\u8be2\u3002<br \/>\n\u6743\u5229\uff1a\u8bbf\u95ee\u3001\u7ea0\u6b63\u548c\u5220\u9664\u6570\u636e\u4ee5\u53ca\u5176\u4ed6\u6743\u5229\uff0c\u5982\u9644\u52a0\u4fe1\u606f\u4e2d\u6240\u8ff0<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-offset-0 vc_col-md-offset-0 vc_col-sm-offset-0\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f159-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/zh\/wp-json\/wp\/v2\/pages\/3694#wpcf7-f159-o1\" method=\"post\" class=\"wpcf7-form init cf7_custom_style_2 wpcf7-acceptance-as-validation\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/zh\/wp-json\/wp\/v2\/pages\/3694#wpcf7-f159-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"159\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f159-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> \u516c\u53f8<br \/>\n    <span class=\"wpcf7-form-control-wrap your-company\"><input type=\"text\" name=\"your-company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u5168\u540d\uff08\u5fc5\u586b\uff09<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u7535\u5b50\u90ae\u4ef6\uff08\u5fc5\u586b\uff09<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u4e8b\u52a1<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u4fe1\u606f<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><span class=\"wpcf7-form-control-wrap your-consent\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"your-consent\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">\u6211\u5df2\u9605\u8bfb\u5e76\u63a5\u53d7 <a href=\"https:\/\/www.cabezaldeimpresion.com\/zh\/politica-de-privacidad-2\/\" target=\"_blank\">\u9690\u79c1\u653f\u7b56\u3002<\/span><\/label><\/span><\/span><\/span><\/p>\n<p><input type=\"submit\" value=\"\u53d1\u9001\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"zh\"\/><\/form><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_gmaps_widget wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"wpb_map_wraper\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2952.503750243178!2d-8.669051284546633!3d42.26776897919313!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd2f632ec9dcee5b%3A0x5471c866f4687353!2sAv.%20Redondela%2C%2060%2C%2062%20Bajo%2C%2036320%20Redondela%2C%20Pontevedra!5e0!3m2!1sen!2ses!4v1599824342516!5m2!1sen!2ses\" width=\"1280\" height=\"720\" frameborder=\"0\" style=\"border:0;\" allowfullscreen=\"\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"\u5728\u8fd9\u91cc\u627e\u5230\u6211\u4eec Printheads Avenida Redondela 60. 36320 - Chapela (Redondela) \u897f\u73ed\u7259 +34 986335022 \u5728\u53d1\u9001\u6b64\u95ee\u5377\u4e4b\u524d\uff0c\u60a8\u5fc5\u987b\u63a5\u53d7\u6211\u4eec\u7684\u9690\u79c1\u653f\u7b56\u3002\u6570\u636e\u4fdd\u62a4\u7684\u57fa\u672c\u4fe1\u606f \u8d1f\u8d23\u4eba\uff1aBELTRAN MU\u00d1OZ, .SL \u76ee\u7684\uff1a\u56de\u590d\u5411...\u63d0\u51fa\u7684\u67e5\u8be2","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/pages\/3694"}],"collection":[{"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/comments?post=3694"}],"version-history":[{"count":20,"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/pages\/3694\/revisions"}],"predecessor-version":[{"id":3878,"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/pages\/3694\/revisions\/3878"}],"wp:attachment":[{"href":"https:\/\/www.cabezaldeimpresion.com\/zh\/wp-json\/wp\/v2\/media?parent=3694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}