{"id":3694,"date":"2020-03-05T09:59:24","date_gmt":"2020-03-05T09:59:24","guid":{"rendered":"http:\/\/cabezaldeimpresion.belgraf.es\/?page_id=3694"},"modified":"2021-10-19T11:51:03","modified_gmt":"2021-10-19T11:51:03","slug":"contacto","status":"publish","type":"page","link":"https:\/\/www.cabezaldeimpresion.com\/hi\/contacto\/","title":{"rendered":"\u0938\u0902\u092a\u0930\u094d\u0915 \u0915\u0930\u0947\u0902"},"content":{"rendered":"<div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1581064010419 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-offset-0 vc_col-md-offset-0 vc_col-sm-offset-0\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5>\u0939\u092e\u0947\u0902 \u092f\u0939\u093e\u0901 \u0916\u094b\u091c\u0947\u0902<\/h5>\n\n\t\t<\/div> \n\t<\/div> \t<div class=\"vc_empty_space\"  style=\"height: 30px\" ><span\r\n\t\t\tclass=\"vc_empty_space_inner\">\r\n\t\t\t<span class=\"empty_space_image\"  ><\/span>\r\n\t\t<\/span><\/div>\r\n\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>\u0938\u0902\u092a\u094d\u0930\u0924\u0940\u0915 \u091b\u092a\u093e\u0908 \u092f\u0902\u0924\u094d\u0930 \u092e\u0947\u0902 \u0915\u093e\u0917\u091c \u092a\u0930 \u0938\u094d\u092f\u093e\u0939\u0940 \u0921\u093e\u0932\u0928\u0947 \u0915\u0940 \u092f\u0902\u0924\u094d\u0930\u092a\u094d\u0930\u0923\u093e\u0932\u0940<\/strong><\/p>\n\n\t\t<\/div> \n\t<\/div> \t<div class=\"vc_empty_space\"  style=\"height: 20px\" ><span\r\n\t\t\tclass=\"vc_empty_space_inner\">\r\n\t\t\t<span class=\"empty_space_image\"  ><\/span>\r\n\t\t<\/span><\/div>\r\n\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><a href=\"https:\/\/www.google.com\/maps\/place\/Av.+Redondela,+60,+36320+Redondela,+Pontevedra\/@42.2677729,-8.6690513,17z\/data=!3m1!4b1!4m5!3m4!1s0xd2f632ec9dcee5b:0xec89991cd3a2aa77!8m2!3d42.267769!4d-8.6668626\" target=\"_blank\" rel=\"noopener noreferrer\"><i class=\"fa fa-map\"><\/i> \u090f\u0935\u0947\u0928\u093f\u0921\u093e \u0930\u0947\u0921\u094b\u0902\u0921\u0947\u0932\u093e 60. 36320 - \u091a\u0948\u092a\u0947\u0932\u093e (\u0930\u0947\u0921\u094b\u0902\u0921\u0947\u0932\u093e) \u0938\u094d\u092a\u0947\u0928<\/a><\/p>\n\n\t\t<\/div> \n\t<\/div> \t<div class=\"vc_empty_space\"  style=\"height: 20px\" ><span\r\n\t\t\tclass=\"vc_empty_space_inner\">\r\n\t\t\t<span class=\"empty_space_image\"  ><\/span>\r\n\t\t<\/span><\/div>\r\n\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><a href=\"tel:+34986335022\"><i class=\"fa fa-phone\"><\/i> +34 986335022<\/a><\/p>\n\n\t\t<\/div> \n\t<\/div> <div class=\"vc_text_separator wpb_content_element full separator_align_center\"><div style=''><span><\/span><\/div><\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u0906\u092a\u0915\u094b \u0939\u092e\u093e\u0930\u0947 \u0915\u094b \u0938\u094d\u0935\u0940\u0915\u093e\u0930 \u0915\u0930\u0928\u0947 \u0915\u0940 \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0939\u0948 <a href=\"https:\/\/www.cabezaldeimpresion.com\/hi\/politica-de-privacidad-2\/\">\u0917\u094b\u092a\u0928\u0940\u092f\u0924\u093e \u0928\u0940\u0924\u093f <\/a> \u0907\u0938 \u092a\u094d\u0930\u0936\u094d\u0928\u093e\u0935\u0932\u0940 \u0915\u094b \u092a\u094d\u0930\u0938\u094d\u0924\u0941\u0924 \u0915\u0930\u0928\u0947 \u0938\u0947 \u092a\u0939\u0932\u0947\u0964<\/p>\n<p><strong>\u0921\u0947\u091f\u093e \u0938\u0902\u0930\u0915\u094d\u0937\u0923 \u092a\u0930 \u092c\u0941\u0928\u093f\u092f\u093e\u0926\u0940 \u091c\u093e\u0928\u0915\u093e\u0930\u0940<\/strong><br \/>\n\u091c\u093f\u092e\u094d\u092e\u0947\u0926\u093e\u0930: BELTRAN MU\u00d1OZ, .SL<br \/>\n\u0909\u0926\u094d\u0926\u0947\u0936\u094d\u092f: \u0935\u0947\u092c \u092b\u0949\u0930\u094d\u092e \u0915\u0947 \u092e\u093e\u0927\u094d\u092f\u092e \u0938\u0947 \u0909\u0920\u093e\u090f \u0917\u090f \u092a\u094d\u0930\u0936\u094d\u0928\u094b\u0902 \u0915\u093e \u0909\u0924\u094d\u0924\u0930 \u0926\u0947\u0902\u0964<br \/>\n\u0905\u0927\u093f\u0915\u093e\u0930: \u0905\u0924\u093f\u0930\u093f\u0915\u094d\u0924 \u091c\u093e\u0928\u0915\u093e\u0930\u0940 \u092e\u0947\u0902 \u092c\u0924\u093e\u090f \u0917\u090f \u0905\u0928\u0941\u0938\u093e\u0930 \u0921\u0947\u091f\u093e, \u0938\u093e\u0925 \u0939\u0940 \u0905\u0928\u094d\u092f \u0905\u0927\u093f\u0915\u093e\u0930\u094b\u0902 \u0924\u0915 \u092a\u0939\u0941\u0902\u091a, \u0938\u0941\u0927\u093e\u0930 \u0914\u0930 \u0939\u091f\u093e\u090f\u0902<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-offset-0 vc_col-md-offset-0 vc_col-sm-offset-0\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f159-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/hi\/wp-json\/wp\/v2\/pages\/3694#wpcf7-f159-o1\" method=\"post\" class=\"wpcf7-form init cf7_custom_style_2 wpcf7-acceptance-as-validation\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/hi\/wp-json\/wp\/v2\/pages\/3694#wpcf7-f159-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"159\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f159-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> \u0915\u0902\u092a\u0928\u0940<br \/>\n    <span class=\"wpcf7-form-control-wrap your-company\"><input type=\"text\" name=\"your-company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u092a\u0942\u0930\u093e \u0928\u093e\u092e (\u0906\u0935\u0936\u094d\u092f\u0915)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u0908\u092e\u0947\u0932 (\u0905\u0928\u093f\u0935\u093e\u0930\u094d\u092f)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u091a\u0915\u094d\u0915\u0930<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> \u0938\u0902\u0926\u0947\u0936<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><span class=\"wpcf7-form-control-wrap your-consent\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"your-consent\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">\u092e\u0948\u0902\u0928\u0947 \u092a\u0922\u093c\u093e \u0939\u0948 \u0914\u0930 \u0938\u094d\u0935\u0940\u0915\u093e\u0930 \u0915\u093f\u092f\u093e \u0939\u0948 <a href=\"https:\/\/www.cabezaldeimpresion.com\/hi\/politica-de-privacidad-2\/\" target=\"_blank\">\u0917\u094b\u092a\u0928\u0940\u092f\u0924\u093e \u0928\u0940\u0924\u093f\u0964<\/span><\/label><\/span><\/span><\/span><\/p>\n<p><input type=\"submit\" value=\"\u0938\u0902\u0926\u0947\u0936\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"hi\"\/><\/form><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_gmaps_widget wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"wpb_map_wraper\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2952.503750243178!2d-8.669051284546633!3d42.26776897919313!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd2f632ec9dcee5b%3A0x5471c866f4687353!2sAv.%20Redondela%2C%2060%2C%2062%20Bajo%2C%2036320%20Redondela%2C%20Pontevedra!5e0!3m2!1sen!2ses!4v1599824342516!5m2!1sen!2ses\" width=\"1280\" height=\"720\" frameborder=\"0\" style=\"border:0;\" allowfullscreen=\"\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"\u0939\u092e\u0947\u0902 \u092f\u0939\u093e\u0902 \u0916\u094b\u091c\u0947\u0902 \u092a\u094d\u0930\u093f\u0902\u091f \u0939\u0947\u0921\u094d\u0938 \u090f\u0935\u0947\u0928\u093f\u0921\u093e \u0930\u0947\u0921\u094b\u0902\u0921\u0947\u0932\u093e 60. 36320 - \u091a\u0948\u092a\u0932\u093e (\u0930\u0947\u0921\u094b\u0902\u0921\u0947\u0932\u093e) \u0938\u094d\u092a\u0947\u0928 +34 986335022 \u0907\u0938 \u092a\u094d\u0930\u0936\u094d\u0928\u093e\u0935\u0932\u0940 \u0915\u094b \u092d\u0947\u091c\u0928\u0947 \u0938\u0947 \u092a\u0939\u0932\u0947 \u0906\u092a\u0915\u094b \u0939\u092e\u093e\u0930\u0940 \u0917\u094b\u092a\u0928\u0940\u092f\u0924\u093e \u0928\u0940\u0924\u093f \u0915\u094b \u0938\u094d\u0935\u0940\u0915\u093e\u0930 \u0915\u0930\u0928\u093e \u0939\u094b\u0917\u093e\u0964 \u0921\u0947\u091f\u093e \u0938\u0902\u0930\u0915\u094d\u0937\u0923 \u092a\u0930 \u092c\u0941\u0928\u093f\u092f\u093e\u0926\u0940 \u091c\u093e\u0928\u0915\u093e\u0930\u0940 \u091c\u093f\u092e\u094d\u092e\u0947\u0926\u093e\u0930: BELTRAN MU\u00d1OZ, .SL \u0909\u0926\u094d\u0926\u0947\u0936\u094d\u092f: \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u090f \u0917\u090f \u092a\u094d\u0930\u0936\u094d\u0928\u094b\u0902 \u0915\u093e \u0909\u0924\u094d\u0924\u0930 \u0926\u0947\u0902...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/pages\/3694"}],"collection":[{"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/comments?post=3694"}],"version-history":[{"count":20,"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/pages\/3694\/revisions"}],"predecessor-version":[{"id":3878,"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/pages\/3694\/revisions\/3878"}],"wp:attachment":[{"href":"https:\/\/www.cabezaldeimpresion.com\/hi\/wp-json\/wp\/v2\/media?parent=3694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}